{"id":24777,"date":"2021-03-24T23:12:13","date_gmt":"2021-03-24T22:12:13","guid":{"rendered":"https:\/\/www.icscyl.com\/mileon\/?p=24777"},"modified":"2021-03-24T23:12:17","modified_gmt":"2021-03-24T22:12:17","slug":"sesiones-bibliograficas-de-residentes-temas-de-neumologia-y-deprescripcion-farmacologica","status":"publish","type":"post","link":"https:\/\/www.icscyl.com\/mileon\/residentes\/2021-03-24\/sesiones-bibliograficas-de-residentes-temas-de-neumologia-y-deprescripcion-farmacologica\/","title":{"rendered":"Sesiones bibliogr\u00e1ficas de residentes: temas de neumolog\u00eda y deprescripci\u00f3n farmacol\u00f3gica"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.icscyl.com\/mileon\/wp-content\/uploads\/2021\/03\/image.jpeg\" alt=\"\" class=\"wp-image-24785\" width=\"237\" height=\"110\" srcset=\"https:\/\/www.icscyl.com\/mileon\/wp-content\/uploads\/2021\/03\/image.jpeg 328w, https:\/\/www.icscyl.com\/mileon\/wp-content\/uploads\/2021\/03\/image-300x141.jpeg 300w\" sizes=\"auto, (max-width: 237px) 100vw, 237px\" \/><\/figure><\/div>\n\n\n\n<p>Nueva entrada con sesiones del primer trimestre del a\u00f1o de nuestros residentes sobre diferentes temas, en esta ocasi\u00f3n en su mayor\u00eda centrados en la neumolog\u00eda. As\u00ed, en primer lugar una sesi\u00f3n sobre el manejo del tromboembolismo pulmonar realizada por la Dra. Romero (R1), en la que se revisan las gu\u00edas de la Sociedad Europea de Cardiolog\u00eda publicadas en 2019. A continuaci\u00f3n una actualizaci\u00f3n sobre la infecci\u00f3n por Pneumocystis jirovecii realizada por la Dra. Hontoria (R4), donde se realiza un amplio repaso de esta entidad, centr\u00e1ndose en el diagn\u00f3stico y tratamiento. Despu\u00e9s una revisi\u00f3n sobre una enfermedad poco frecuente en nuestra pr\u00e1ctica cl\u00ednica como la enfermedad venoclusiva pulmonar realizada por el Dr. Ortiz (R1). Por \u00faltimo y saliendo del bloque de neumolog\u00eda, una revisi\u00f3n sobre la deprescripci\u00f3n farmacol\u00f3gica realizada por la Dra. Su\u00e1rez (R3), que repasa a qui\u00e9n deprescribir y cu\u00e1les son los grupos farmacol\u00f3gicos en los que deber\u00edamos plantearnos la deprescripci\u00f3n.<\/p>\n\n\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/www.icscyl.com\/mileon\/wp-content\/uploads\/2021\/03\/Dra-Romero-Tromboembolismo-pulmonar-sesbibl-Ene21.pdf\">Dra-Romero-Tromboembolismo-pulmonar-sesbibl-Ene21<\/a><a href=\"https:\/\/www.icscyl.com\/mileon\/wp-content\/uploads\/2021\/03\/Dra-Romero-Tromboembolismo-pulmonar-sesbibl-Ene21.pdf\" class=\"wp-block-file__button\" download>Descarga<\/a><\/div>\n\n\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/www.icscyl.com\/mileon\/wp-content\/uploads\/2021\/03\/Dra-Hontoria-Infecciones-por-pneumocistis-jirovecii-sesbibl-Ene21.pdf\">Dra-Hontoria-Infecciones-por-pneumocistis-jirovecii-sesbibl-Ene21<\/a><a href=\"https:\/\/www.icscyl.com\/mileon\/wp-content\/uploads\/2021\/03\/Dra-Hontoria-Infecciones-por-pneumocistis-jirovecii-sesbibl-Ene21.pdf\" class=\"wp-block-file__button\" download>Descarga<\/a><\/div>\n\n\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/www.icscyl.com\/mileon\/wp-content\/uploads\/2021\/03\/Dra-Suarez-Deprescripcion-sesbibl-mar21.pdf\">Dra-Suarez-Deprescripcion-sesbibl-mar21<\/a><a href=\"https:\/\/www.icscyl.com\/mileon\/wp-content\/uploads\/2021\/03\/Dra-Suarez-Deprescripcion-sesbibl-mar21.pdf\" class=\"wp-block-file__button\" download>Descarga<\/a><\/div>\n\n\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/www.icscyl.com\/mileon\/wp-content\/uploads\/2021\/03\/Dr-Ortiz-sesbibl-Feb21.pdf\">Dr-Ortiz-sesbibl-Feb21<\/a><a href=\"https:\/\/www.icscyl.com\/mileon\/wp-content\/uploads\/2021\/03\/Dr-Ortiz-sesbibl-Feb21.pdf\" class=\"wp-block-file__button\" download>Descarga<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nueva entrada con sesiones del primer trimestre del a\u00f1o de nuestros residentes sobre diferentes temas, en esta ocasi\u00f3n en su mayor\u00eda centrados en la neumolog\u00eda. As\u00ed, en primer lugar una sesi\u00f3n sobre el manejo del tromboembolismo pulmonar realizada por la Dra. Romero (R1), en la que se revisan las gu\u00edas de la Sociedad Europea de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[721],"tags":[1086,1087],"class_list":["post-24777","post","type-post","status-publish","format-standard","hentry","category-residentes","tag-ortiz","tag-romero"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.icscyl.com\/mileon\/wp-json\/wp\/v2\/posts\/24777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.icscyl.com\/mileon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.icscyl.com\/mileon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.icscyl.com\/mileon\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.icscyl.com\/mileon\/wp-json\/wp\/v2\/comments?post=24777"}],"version-history":[{"count":0,"href":"https:\/\/www.icscyl.com\/mileon\/wp-json\/wp\/v2\/posts\/24777\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.icscyl.com\/mileon\/wp-json\/wp\/v2\/media?parent=24777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.icscyl.com\/mileon\/wp-json\/wp\/v2\/categories?post=24777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.icscyl.com\/mileon\/wp-json\/wp\/v2\/tags?post=24777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}