{"id":13585,"date":"2019-02-05T23:11:03","date_gmt":"2019-02-05T22:11:03","guid":{"rendered":"https:\/\/mileon.wordpress.com\/?p=13585"},"modified":"2019-02-05T23:11:03","modified_gmt":"2019-02-05T22:11:03","slug":"sesion-bibliografica-del-1-de-febrero-de-2019","status":"publish","type":"post","link":"https:\/\/www.icscyl.com\/mileon\/sesiones-bibliograficas\/2019-02-05\/sesion-bibliografica-del-1-de-febrero-de-2019\/","title":{"rendered":"Sesi\u00f3n Bibliogr\u00e1fica del 1 de Febrero de 2019."},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mileon.files.wordpress.com\/2019\/02\/imagen1-1.png?w=237\" alt=\"\" class=\"wp-image-13586\" width=\"211\" height=\"123\" \/><\/figure><\/div>\n\n\n<p>La Dra. Isabel Muinelo hace una amplia revisi\u00f3n de temas de actualidad relacionados con la hipertensi\u00f3n y su tratamiento. La primera parte de la presentaci\u00f3n se centra en las gu\u00edas sobre el manejo de la HTA publcadas recientemente (<em>ESC\/ESH Guidelines for the treatment of arterial hypertensi\u00f3n<\/em>). Destaca las principales novedades en diagn\u00f3stico y escalas de riesgo (se incluye la fibrilaci\u00f3n auricular como criterio de enfermedad establecida) y las recomendaciones de tratamiento de forma resumida. En la segunda parte, se analizan una serie de trabajos referidos a IECAs y riesgo de c\u00e1ncer de pulm\u00f3n, hidroclorotiazida y riesgo de c\u00e1ncer de piel, no melanoma, y de labio. Se recuerdan los problemas de desabastecimiento de algunos f\u00e1rmacos y los problemas que motivaron la retirada del valsartan\/irbesartan. Por \u00faltimo, dos trabajos que analizan el riesgo cadiovascular y la mortalidad en los pacientes con cifras elevadas de HDL.<\/p>\n\n\n<p>Para ver la presentaci\u00f3n completa <a href=\"https:\/\/mileon2.files.wordpress.com\/2019\/02\/f-sesion-dc3ada-1-febrero-2019-hta-.pdf\">pinchar AQU\u00cd<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Dra. Isabel Muinelo hace una amplia revisi\u00f3n de temas de actualidad relacionados con la hipertensi\u00f3n y su tratamiento. La primera parte de la presentaci\u00f3n se centra en las gu\u00edas sobre el manejo de la HTA publcadas recientemente (ESC\/ESH Guidelines for the treatment of arterial hypertensi\u00f3n). Destaca las principales novedades en diagn\u00f3stico y escalas de [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[722],"tags":[947],"class_list":["post-13585","post","type-post","status-publish","format-standard","hentry","category-sesiones-bibliograficas","tag-muinelo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.icscyl.com\/mileon\/wp-json\/wp\/v2\/posts\/13585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.icscyl.com\/mileon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.icscyl.com\/mileon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.icscyl.com\/mileon\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.icscyl.com\/mileon\/wp-json\/wp\/v2\/comments?post=13585"}],"version-history":[{"count":0,"href":"https:\/\/www.icscyl.com\/mileon\/wp-json\/wp\/v2\/posts\/13585\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.icscyl.com\/mileon\/wp-json\/wp\/v2\/media?parent=13585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.icscyl.com\/mileon\/wp-json\/wp\/v2\/categories?post=13585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.icscyl.com\/mileon\/wp-json\/wp\/v2\/tags?post=13585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}